{"id":430,"date":"2016-03-12T11:26:10","date_gmt":"2016-03-12T10:26:10","guid":{"rendered":"http:\/\/gilbertbrands.de\/blog\/?p=430"},"modified":"2016-03-12T11:26:35","modified_gmt":"2016-03-12T10:26:35","slug":"welches-miese-spiel-spielt-hier-der-innenminister","status":"publish","type":"post","link":"https:\/\/gilbertbrands.de\/blog\/2016\/03\/12\/welches-miese-spiel-spielt-hier-der-innenminister\/","title":{"rendered":"Welches (miese) Spiel spielt hier der Innenminister ?"},"content":{"rendered":"<p>Innenminister de Maizi\u00e8re fordert eine strengere Passkontrolle, um (O-Ton NDR-Nachrichten)<\/p>\n<blockquote><p>festzustellen, wann eine Person mit einem Visum ein Land betritt. Au\u00dferdem k\u00f6nnen biometrische Daten helfen, zu erkennen, wenn jemand seine Visumsg\u00fcltigkeit \u00fcberzieht<\/p><\/blockquote>\n<p><!--more--><\/p>\n<p>Mit &#8222;biometrischen Daten&#8220; sind laut Nachrichten ausdr\u00fccklich Fingerabdr\u00fccke und DNA gemeint. Solche Meldungen sollten bei jedem die Alarmglocken aufs Lauteste erschallten lassen:<\/p>\n<ul>\n<li>P\u00e4sse werden schon lange nicht mehr nur sichtkontrolliert, sondern eingescant. Argumente wie &#8222;beim Ticketwechsel wird nur der Prim\u00e4rinhaber registriert&#8220; geh\u00f6ren daher in die Rubrik Grimmsche M\u00e4rchen, genauso wie eine mangelnde Kontrolle und Registrierung \u00fcberhaupt.<\/li>\n<li>Fingerabdr\u00fccke sind auf Betreiben der USA inzwischen Bestandteil der P\u00e4sse, <strong>aber nicht DNA!!<\/strong><\/li>\n<li>Eine \u00dcberschreitung der Visag\u00fcltigkeit kann durch die registrierten Passdaten erfolgen; biometrische Daten sind nicht notwendig.<\/li>\n<\/ul>\n<p>Biometrische Daten machen \u00fcberhaupt erst einen Sinn, wenn sie mit einer fl\u00e4chendeckenden nahezu l\u00fcckenlosen \u00dcberwachung jedes einzelnen verbunden sind. Fingerabdr\u00fccke und insbesondere DNA sind dabei gar nicht so einfach zu messen. <strong>Solche Ma\u00dfnahmen wie die von de Maizi\u00e8re vorgeschlagenen machen nur Sinn, wenn die \u00fcbelsten Szenarien, die ich in meinen B\u00fcchern &#8222;NSA, BND &amp; Co.&#8220; sowie &#8222;Die ausgesp\u00e4hte Gesellschaft&#8220; beschrieben habe, umgesetzt werden<\/strong>. Nicht, dass sie es nicht vermutlich zum gr\u00f6\u00dften Teil schon sind, aber bislang sind das Methoden der Nachrichtendienste, die nicht legal sind oder legalisiert werden k\u00f6nnen. Aber nun streben die politisch Verantwortlichen offenbar zus\u00e4tzliche die vollst\u00e4ndige Legalisierung der Abschaffung jeglicher Privatsph\u00e4re an.<\/p>\n<span class=\"hit-count\">Views: 3462<\/span>\n","protected":false},"excerpt":{"rendered":"<p>Innenminister de Maizi\u00e8re fordert eine strengere Passkontrolle, um (O-Ton NDR-Nachrichten) festzustellen, wann eine Person mit einem Visum ein Land betritt. Au\u00dferdem k\u00f6nnen biometrische Daten helfen, zu erkennen, wenn jemand seine Visumsg\u00fcltigkeit \u00fcberzieht Download Artikel als PDF<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,5],"tags":[],"class_list":["post-430","post","type-post","status-publish","format-standard","hentry","category-geschichte","category-it-sicherheit"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/posts\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/comments?post=430"}],"version-history":[{"count":2,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/posts\/430\/revisions"}],"predecessor-version":[{"id":432,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/posts\/430\/revisions\/432"}],"wp:attachment":[{"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/media?parent=430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/categories?post=430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/tags?post=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}