{"id":12820,"date":"2026-05-11T09:20:16","date_gmt":"2026-05-11T07:20:16","guid":{"rendered":"https:\/\/gilbertbrands.de\/blog\/?p=12820"},"modified":"2026-05-11T09:20:17","modified_gmt":"2026-05-11T07:20:17","slug":"ist-der-mensch-nur-noch-biomuell","status":"publish","type":"post","link":"https:\/\/gilbertbrands.de\/blog\/2026\/05\/11\/ist-der-mensch-nur-noch-biomuell\/","title":{"rendered":"Ist der Mensch nur noch Biom\u00fcll?"},"content":{"rendered":"\n<p>Etwas gro\u00dfspurig hei\u00dft es zu Beginn des Grundgesetzes:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Artikel 1<br><br>(1) Die W\u00fcrde des Menschen ist unantastbar. Sie zu achten und zu sch\u00fctzen ist Verpflichtung aller staatlichen Gewalt.<br><br>(2) Das Deutsche Volk bekennt sich darum zu unverletzlichen und unver\u00e4u\u00dferlichen Menschenrechten als Grundlage jeder menschlichen Gemeinschaft, des Friedens und der Gerechtigkeit in der Welt.<\/pre>\n\n\n\n<!--more-->\n\n\n\n<p>Wenn man sich die heute \u00fcblichen Werkzeuge des Staates anschaut, die in pers\u00f6nlichen Sanktionen gegen Staatsb\u00fcrger wie H\u00fcseyin Dogru und seiner Familie m\u00fcnden, ist das wohl deutlich zu gro\u00dfspurig. Noch mal an den Fall Dogru erinnert: die Familie erfuhr erst aus der Presse davon, nachdem die Konten begr\u00fcndungslos gesperrt wurden. Sippenhaftm\u00e4\u00dfig wurde der mit Zwillingen hochschwangeren Frau die medizinische Betreuung verweigert, sp\u00e4ter sogar ihr Konto zeitweise gesperrt. Im angeblichen Rechtsstaat Bundesrepublik ist es juristisch v\u00f6llig legal, so etwas ohne Begr\u00fcndung, ohne Anh\u00f6rung und ohne echte Rechtsmittel zu machen. Selbst die Vertretung der Betroffenen durch einen Anwalt f\u00fcr Versuche, doch etwas zu unternehmen, ist nach deutschem Recht illegal.<\/p>\n\n\n\n<p>Dogru ist Journalist und die einzige \u00f6ffentliche Reaktion ist ein wenig Aufregung \u00fcber einen Angriff auf die journalistischen Freiheiten. Das ist derart zynisch und l\u00e4cherlich, dass es durch Satire kaum \u00fcberboten werden kann. Das Tierschutzgesetz verbietet das Qu\u00e4len von Tieren bei Strafe. H\u00e4tte man Vergleichbares mit einem Tier gemacht &#8211; Aussetzen eines Kanarienvogels (oder eines Hundes oder einer Katze) im Winter auf einem umschlossenen Hof ohne Nahrung &#8211; w\u00fcrde man sich im Knast wiederfinden. Bei Menschen hingegen reicht es inzwischen noch nicht mal f\u00fcr die Schutzrechte, die Tiere genie\u00dfen. Man darf ihn samt seiner Sippe verhungern oder erfrieren lassen und belangt noch obendrein die mit Strafen, die das zu verhindern suchen. Das ist nichts anderes als die komplette Streichung des gro\u00dfspurigen Art. 1 GG. Der Mensch wird ohne W\u00fcrde zum Biom\u00fcll, wenn es der Obrigkeit in den Kram passt.<\/p>\n\n\n\n<p>Etwas n\u00e4her zumindest am Tierschutzgesetz sind die Kriege, die aktiv gef\u00fchrt werden oder zu denen aufgestachelt wird. Vom Tierschutzgesetz erlaubt ist das Keulen wirtschaftlicher Best\u00e4nde. Tritt ein Verdachtsfall von Vogelgrippe unter 100.000 H\u00fchner eines Hofs auf, wird der gesamte Bestand gekeult. Man k\u00f6nnte nat\u00fcrlich abwarten und die H\u00fchner oder andere Hoftiere die Krankheit aussitzen lassen. Epidemiologisch sollte das die Resistenz f\u00f6rdern, das Hauptargument ist allerdings, dass es wirtschaftlich g\u00fcnstiger ist, den Krankheitsausbruch (es reicht ein Verdacht) gar nicht abzuwarten, sondern den Bestand sofort zu ersetzen. <\/p>\n\n\n\n<p>Das l\u00e4sst sich blendend auf Kriege \u00fcbertragen: statt darauf zu setzen, dass sich Ukrainer und Russen oder wahlweise Israelis und Pal\u00e4stinenser friedlich einigen k\u00f6nnen, ist es wirtschaftlich g\u00fcnstiger, die Ukrainer-, Russen- und Pal\u00e4stinenserbest\u00e4nde zu keulen. Zul\u00e4ssig nach dem Tierschutzgesetz. <\/p>\n\n\n\n<p>Der individuelle Mensch wird heute vom Staat nicht mehr in der ihm zustehende W\u00fcrde wahrgenommen, sondern zunehmend als Pr\u00e4biom\u00fcllmasse. Und dann wundern sich die Gro\u00dfkopfeten auch noch, wenn man sie mit zunehmendem Ekelgef\u00fchl anstatt mit Zustimmung betrachtet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Etwas gro\u00dfspurig hei\u00dft es zu Beginn des Grundgesetzes: Artikel 1(1) Die W\u00fcrde des Menschen ist unantastbar. Sie zu achten und zu sch\u00fctzen ist Verpflichtung aller staatlichen Gewalt.(2) Das Deutsche Volk bekennt sich darum zu unverletzlichen und unver\u00e4u\u00dferlichen Menschenrechten als Grundlage jeder menschlichen Gemeinschaft, des Friedens und der Gerechtigkeit in der Welt. Download Artikel als PDF<\/p>\n","protected":false},"author":1,"featured_media":12821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/posts\/12820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/comments?post=12820"}],"version-history":[{"count":2,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/posts\/12820\/revisions"}],"predecessor-version":[{"id":12823,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/posts\/12820\/revisions\/12823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/media\/12821"}],"wp:attachment":[{"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/media?parent=12820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/categories?post=12820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gilbertbrands.de\/blog\/wp-json\/wp\/v2\/tags?post=12820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}